{"id":11364,"date":"2025-10-08T11:39:14","date_gmt":"2025-10-08T09:39:14","guid":{"rendered":"https:\/\/www.bastidapelletteria.com\/main\/?post_type=product&#038;p=11364"},"modified":"2026-03-18T17:52:40","modified_gmt":"2026-03-18T16:52:40","slug":"zaino-porta-pc-14-personalizzabile-3","status":"publish","type":"product","link":"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/","title":{"rendered":"Zaino porta pc 14&#8243; personalizzabile"},"content":{"rendered":"<p>La collezione Blue Square \u00e8 realizzata in vitello con conciatura minerale. Il sistema tradizionale di concia mantiene inalterata la bellezza della pelle negli anni. I bordi a taglio vivo, dipinti a mano in azzurro, vivacizzano il carattere business della collezione e rappresentano un elemento distintivo di grande riconoscibilit\u00e0<\/p>\n<p><strong>Specifiche tecniche<\/strong><\/p>\n<p>Numero comparti: 2<br \/>\nPu\u00f2 contenere: notebook da 14&#8243;<br \/>\nCaratteristiche porta PC: Shock Absorber<br \/>\nPorta iPad\u00ae 10,2&#8221;Air 10,9&#8221;Pro 11&#8221;: fisso<br \/>\nTasca porta AirPods\u00ae: S\u00ec<br \/>\nMateriale: pelle<br \/>\nFodera interna: 100% Poliestere<br \/>\nSistema di sicurezza: Cavo in acciaio e lucchetto con combinazione<br \/>\nTipologia manici: fissi<br \/>\nTasche per ricarica ad induzione: si<br \/>\nTasca power bank: S\u00ec<br \/>\nPorta occhiali: con tasca<br \/>\nLitraggio: 16<br \/>\nDotato di Tag personalizzabile: S\u00ec<br \/>\nCodice prodotto: CA6591B2<br \/>\nCarbon Neutral: 42,37 kgCO2eq<br \/>\nDimensioni: 29.0 x 39.0 x 17.0 (cm)<br \/>\nPeso: 1393 gr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zaino porta pc e iPad\u00ae personalizzabile con cavo antifurto, protezioni antiurto e RFID, colore BLU<\/p>\n","protected":false},"featured_media":11397,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[226],"product_tag":[532,531,530,412,529],"class_list":["post-11364","product","type-product","status-publish","has-post-thumbnail","product_brand-piquadro","product_cat-zaini","product_tag-b2","product_tag-office","product_tag-piquadro","product_tag-porta-pc","product_tag-zaino-piquadro","first","instock","sold-individually","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zaino porta pc 14&quot; personalizzabile - Bastida Pelletteria Foligno<\/title>\n<meta name=\"description\" content=\"Zaino Piquadro porta pc e iPad\u00ae personalizzabile con cavo antifurto, protezioni antiurto e RFID, colore BLU\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zaino porta pc 14&quot; personalizzabile - Bastida Pelletteria Foligno\" \/>\n<meta property=\"og:description\" content=\"Zaino Piquadro porta pc e iPad\u00ae personalizzabile con cavo antifurto, protezioni antiurto e RFID, colore BLU\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Bastida Pelletteria Foligno\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bastida.pelletteria\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-18T16:52:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bastidapelletteria.com\/main\/wp-content\/uploads\/2025\/10\/CA6591B2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/prodotto\\\/zaino-porta-pc-14-personalizzabile-3\\\/\",\"url\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/prodotto\\\/zaino-porta-pc-14-personalizzabile-3\\\/\",\"name\":\"Zaino porta pc 14\\\" personalizzabile - Bastida Pelletteria Foligno\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/prodotto\\\/zaino-porta-pc-14-personalizzabile-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/prodotto\\\/zaino-porta-pc-14-personalizzabile-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/CA6591B2-1.jpg\",\"datePublished\":\"2025-10-08T09:39:14+00:00\",\"dateModified\":\"2026-03-18T16:52:40+00:00\",\"description\":\"Zaino Piquadro porta pc e iPad\u00ae personalizzabile con cavo antifurto, protezioni antiurto e RFID, colore BLU\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/prodotto\\\/zaino-porta-pc-14-personalizzabile-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/prodotto\\\/zaino-porta-pc-14-personalizzabile-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/prodotto\\\/zaino-porta-pc-14-personalizzabile-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/CA6591B2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/CA6591B2-1.jpg\",\"width\":1000,\"height\":1180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/prodotto\\\/zaino-porta-pc-14-personalizzabile-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zaino porta pc 14&#8243; personalizzabile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/#website\",\"url\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/\",\"name\":\"Bastida Pelletteria Foligno\",\"description\":\"negozio online di pelletteria, valigeria, borse e accessori dei migliori marchi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/#organization\",\"name\":\"Bastida Pelletteria\",\"url\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/logo-best.png\",\"contentUrl\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/logo-best.png\",\"width\":367,\"height\":98,\"caption\":\"Bastida Pelletteria\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bastidapelletteria.com\\\/main\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bastida.pelletteria\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bastidapelletteria\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zaino porta pc 14\" personalizzabile - Bastida Pelletteria Foligno","description":"Zaino Piquadro porta pc e iPad\u00ae personalizzabile con cavo antifurto, protezioni antiurto e RFID, colore BLU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/","og_locale":"it_IT","og_type":"article","og_title":"Zaino porta pc 14\" personalizzabile - Bastida Pelletteria Foligno","og_description":"Zaino Piquadro porta pc e iPad\u00ae personalizzabile con cavo antifurto, protezioni antiurto e RFID, colore BLU","og_url":"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/","og_site_name":"Bastida Pelletteria Foligno","article_publisher":"https:\/\/www.facebook.com\/bastida.pelletteria\/","article_modified_time":"2026-03-18T16:52:40+00:00","og_image":[{"width":1000,"height":1180,"url":"https:\/\/www.bastidapelletteria.com\/main\/wp-content\/uploads\/2025\/10\/CA6591B2-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/","url":"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/","name":"Zaino porta pc 14\" personalizzabile - Bastida Pelletteria Foligno","isPartOf":{"@id":"https:\/\/www.bastidapelletteria.com\/main\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/#primaryimage"},"image":{"@id":"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bastidapelletteria.com\/main\/wp-content\/uploads\/2025\/10\/CA6591B2-1.jpg","datePublished":"2025-10-08T09:39:14+00:00","dateModified":"2026-03-18T16:52:40+00:00","description":"Zaino Piquadro porta pc e iPad\u00ae personalizzabile con cavo antifurto, protezioni antiurto e RFID, colore BLU","breadcrumb":{"@id":"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/#primaryimage","url":"https:\/\/www.bastidapelletteria.com\/main\/wp-content\/uploads\/2025\/10\/CA6591B2-1.jpg","contentUrl":"https:\/\/www.bastidapelletteria.com\/main\/wp-content\/uploads\/2025\/10\/CA6591B2-1.jpg","width":1000,"height":1180},{"@type":"BreadcrumbList","@id":"https:\/\/www.bastidapelletteria.com\/main\/prodotto\/zaino-porta-pc-14-personalizzabile-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bastidapelletteria.com\/main\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.bastidapelletteria.com\/main\/negozio\/"},{"@type":"ListItem","position":3,"name":"Zaino porta pc 14&#8243; personalizzabile"}]},{"@type":"WebSite","@id":"https:\/\/www.bastidapelletteria.com\/main\/#website","url":"https:\/\/www.bastidapelletteria.com\/main\/","name":"Bastida Pelletteria Foligno","description":"negozio online di pelletteria, valigeria, borse e accessori dei migliori marchi","publisher":{"@id":"https:\/\/www.bastidapelletteria.com\/main\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bastidapelletteria.com\/main\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.bastidapelletteria.com\/main\/#organization","name":"Bastida Pelletteria","url":"https:\/\/www.bastidapelletteria.com\/main\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bastidapelletteria.com\/main\/#\/schema\/logo\/image\/","url":"https:\/\/www.bastidapelletteria.com\/main\/wp-content\/uploads\/2017\/03\/logo-best.png","contentUrl":"https:\/\/www.bastidapelletteria.com\/main\/wp-content\/uploads\/2017\/03\/logo-best.png","width":367,"height":98,"caption":"Bastida Pelletteria"},"image":{"@id":"https:\/\/www.bastidapelletteria.com\/main\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bastida.pelletteria\/","https:\/\/www.instagram.com\/bastidapelletteria\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.bastidapelletteria.com\/main\/wp-json\/wp\/v2\/product\/11364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bastidapelletteria.com\/main\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bastidapelletteria.com\/main\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bastidapelletteria.com\/main\/wp-json\/wp\/v2\/comments?post=11364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bastidapelletteria.com\/main\/wp-json\/wp\/v2\/media\/11397"}],"wp:attachment":[{"href":"https:\/\/www.bastidapelletteria.com\/main\/wp-json\/wp\/v2\/media?parent=11364"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bastidapelletteria.com\/main\/wp-json\/wp\/v2\/product_cat?post=11364"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bastidapelletteria.com\/main\/wp-json\/wp\/v2\/product_tag?post=11364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}